{"id":752,"date":"2025-11-13T14:10:09","date_gmt":"2025-11-13T13:10:09","guid":{"rendered":"https:\/\/synerkos-localcom.local\/privacy-policy\/"},"modified":"2026-05-13T16:36:38","modified_gmt":"2026-05-13T14:36:38","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/synerkos.com\/es\/en\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":-1,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-752","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Policy - Synerkos Nacional<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - Synerkos Nacional\" \/>\n<meta property=\"og:url\" content=\"https:\/\/synerkos.com\/es\/en\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Synerkos Nacional\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T14:36:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/synerkos.com\\\/es\\\/en\\\/privacy-policy\\\/\",\"url\":\"https:\\\/\\\/synerkos.com\\\/es\\\/en\\\/privacy-policy\\\/\",\"name\":\"Privacy Policy - Synerkos Nacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/synerkos.com\\\/es\\\/en\\\/#website\"},\"datePublished\":\"2025-11-13T13:10:09+00:00\",\"dateModified\":\"2026-05-13T14:36:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/synerkos.com\\\/es\\\/en\\\/privacy-policy\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/synerkos.com\\\/es\\\/en\\\/privacy-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/synerkos.com\\\/es\\\/en\\\/privacy-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/synerkos.com\\\/es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/synerkos.com\\\/es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/synerkos.com\\\/es\\\/en\\\/\",\"name\":\"Synerkos Nacional\",\"description\":\"Technical Valve Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/synerkos.com\\\/es\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/synerkos.com\\\/es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/synerkos.com\\\/es\\\/en\\\/#organization\",\"name\":\"Synerkos Nacional\",\"url\":\"https:\\\/\\\/synerkos.com\\\/es\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/synerkos.com\\\/es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/synerkos.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/11\\\/Synerkos_logo.svg\",\"contentUrl\":\"https:\\\/\\\/synerkos.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/11\\\/Synerkos_logo.svg\",\"width\":199,\"height\":44,\"caption\":\"Synerkos Nacional\"},\"image\":{\"@id\":\"https:\\\/\\\/synerkos.com\\\/es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy Policy - Synerkos Nacional","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Privacy Policy - Synerkos Nacional","og_url":"https:\/\/synerkos.com\/es\/en\/privacy-policy\/","og_site_name":"Synerkos Nacional","article_modified_time":"2026-05-13T14:36:38+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/synerkos.com\/es\/en\/privacy-policy\/","url":"https:\/\/synerkos.com\/es\/en\/privacy-policy\/","name":"Privacy Policy - Synerkos Nacional","isPartOf":{"@id":"https:\/\/synerkos.com\/es\/en\/#website"},"datePublished":"2025-11-13T13:10:09+00:00","dateModified":"2026-05-13T14:36:38+00:00","breadcrumb":{"@id":"https:\/\/synerkos.com\/es\/en\/privacy-policy\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/synerkos.com\/es\/en\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/synerkos.com\/es\/en\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/synerkos.com\/es\/en\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/synerkos.com\/es\/en\/#website","url":"https:\/\/synerkos.com\/es\/en\/","name":"Synerkos Nacional","description":"Technical Valve Solutions","publisher":{"@id":"https:\/\/synerkos.com\/es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/synerkos.com\/es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/synerkos.com\/es\/en\/#organization","name":"Synerkos Nacional","url":"https:\/\/synerkos.com\/es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/synerkos.com\/es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/synerkos.com\/es\/wp-content\/uploads\/sites\/2\/2025\/11\/Synerkos_logo.svg","contentUrl":"https:\/\/synerkos.com\/es\/wp-content\/uploads\/sites\/2\/2025\/11\/Synerkos_logo.svg","width":199,"height":44,"caption":"Synerkos Nacional"},"image":{"@id":"https:\/\/synerkos.com\/es\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/synerkos.com\/es\/en\/wp-json\/wp\/v2\/pages\/752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/synerkos.com\/es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/synerkos.com\/es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/synerkos.com\/es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/synerkos.com\/es\/en\/wp-json\/wp\/v2\/comments?post=752"}],"version-history":[{"count":1,"href":"https:\/\/synerkos.com\/es\/en\/wp-json\/wp\/v2\/pages\/752\/revisions"}],"predecessor-version":[{"id":1528,"href":"https:\/\/synerkos.com\/es\/en\/wp-json\/wp\/v2\/pages\/752\/revisions\/1528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/synerkos.com\/es\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/synerkos.com\/es\/en\/wp-json\/wp\/v2\/media?parent=752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}